{"id":7993,"date":"2011-10-24T19:07:16","date_gmt":"2011-10-24T17:07:16","guid":{"rendered":"http:\/\/www.todoheavymetal.com\/?p=7993"},"modified":"2011-10-23T11:58:39","modified_gmt":"2011-10-23T09:58:39","slug":"diario-de-la-gira-mexicana-de-necroberus","status":"publish","type":"post","link":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus","title":{"rendered":"DIARIO DE LA GIRA MEXICANA DE NECROBERUS"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/a7.sphotos.ak.fbcdn.net\/hphotos-ak-ash4\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg\" alt=\"\" width=\"228\" height=\"324\" \/>Sergio, cantante y guitarra de NECROBERUS, se pone en contacto con nosotros y nos manda el diario de la gira que han realizado por tierras mexicanas durante el mes de septiembre, presentando su disco G\u00e9nesis y poco antes de su inminente entrada en el estudio para registrar su segundo disco.<\/p>\n<p>Todo un documento de lo que por all\u00ed vivieron Sergio, Pablo, Jorge y Javi.<\/p>\n<p><em>Jueves 15 de septiembre<\/em><\/p>\n<p><em>Son las 10 de la ma\u00f1ana y nos encontramos en el aeropuerto de Barajas con nuestras t\u00edpicas bromas, risas y con las mochilas cargadas de muchas ilusiones. Hab\u00eda algo diferente en el ambiente, no era el t\u00edpico viaje de gira en cualquier ciudad espa\u00f1ola, era algo especial. Y no es para menos ya que se trata de nuestra primera gira mexicana. Todo un hito en nuestras vidas, donde hemos volcado muchas esperanzas e ilusiones. Incluso con cierta incertidumbre, para ser sinceros, sobre si nuestra m\u00fasica gustar\u00e1 en otro continente.<\/em><\/p>\n<p><em>Seguimos con nuestras bromas en el avi\u00f3n donde nos hinchamos a cervezas mientras charl\u00e1bamos con las azafatas y en otros ratos durmiendo, que se tambi\u00e9n se agradece.<\/em><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"http:\/\/a5.sphotos.ak.fbcdn.net\/hphotos-ak-snc7\/320059_10150435646189848_160086484847_11130662_1256585618_n.jpg\" alt=\"\" width=\"229\" height=\"311\" \/>Al llegar a M\u00e9xico nos reciben los dos miembros de la agencia de management, Alex y Fer, los cuales nos llevan a probar nuestros primeros tacos y a forjar una buena amistad mediante una gran cantidad de cervezas, como debe ser. Hay que celebrar que el 15 de septiembre es el d\u00eda de la independencia de M\u00e9xico, o el Grito, y vemos a trav\u00e9s de la televisi\u00f3n como la plaza del Z\u00f3calo est\u00e1 llena de gente festej\u00e1ndolo.<\/em><\/p>\n<p><em>Viernes 16 de septiembre<\/em><\/p>\n<p><em>El concierto previsto para el viernes 16 en Cuernavaca en la sala Alive se suspende por la raz\u00f3n de que la mayor\u00eda de los mexicanos est\u00e1n de puente y no era conveniente realizarlo. As\u00ed que tras dormir un buen pu\u00f1ado de horas nos marchamos por la tarde a ver un combate de Lucha Libre mexicana. Todo un espect\u00e1culo donde descargar el estr\u00e9s y poder gritar a gusto y en el que en m\u00e1s de una ocasi\u00f3n nos hizo levantarnos de los asientos.<\/em><\/p>\n<p><em>S\u00e1bado 17 de septiembre<\/em><\/p>\n<p><em>El s\u00e1bado fue un d\u00eda duro. Tuvimos que madrugar para marchar al Tianguis Cultural de el Chopo. Es un mercadillo dedicado al rock, metal, punk&#8230; Donde se juntan cada s\u00e1bado gente de todos los estilos a comprar, vender o intercambiar todo tipo de material. Desde tablas de skate, camisetas, mu\u00f1equeras&#8230; hasta miles de discos. La verdad es que decir que simplemente es un mercadillo, no es justo. Ya lleva m\u00e1s de 30 a\u00f1os de vida y se ha convertido en un lugar emblem\u00e1tico en la ciudad. Es un punto de encuentro cultural que ya nos gustar\u00eda a m\u00e1s de uno que existiera en Espa\u00f1a. Ah\u00ed hicimos nuestro primer concierto delante de cientos de personas que deambulan desde las primeras horas de la ma\u00f1ana. Tuvimos 25 minutos para demostrar nuestra m\u00fasica y al final se acercaron muchas personas a hacerse fotos con nosotros, comprar discos y camisetas y pedirnos aut\u00f3grafos. Pudimos comprobar la amabilidad ya no s\u00f3lo del p\u00fablico sino de la organizaci\u00f3n que se portaron genial.<\/em><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"http:\/\/a2.sphotos.ak.fbcdn.net\/hphotos-ak-ash4\/291873_10150499889664848_160086484847_11529833_1763881787_n.jpg\" alt=\"\" width=\"324\" height=\"243\" \/>Por la tarde nos desplazamos al centro hist\u00f3rico, a dos calles de la plaza del z\u00f3calo para hacer nuestro segundo concierto en el Club Atl\u00e1ntico, un bar m\u00e1s tranquilo, donde la gente se sentaba en taburetes a tomarse una copa tranquilamente. Sonamos muy bien y eso la gente lo agradeci\u00f3 donde tambi\u00e9n se acercaron a saludarnos y pedirnos aut\u00f3grafos y fotos.<\/em><\/p>\n<p><em>Domingo 18 de septiembre<\/em><\/p>\n<p><em>El domingo por la ma\u00f1ana lo aprovechamos en acercarnos al Z\u00f3calo para darnos una vuelta y hacer algo de turismo. Ya por la tarde nos acercamos a las oficinas de el peri\u00f3dico La Raz\u00f3n, que no tiene ninguna relaci\u00f3n con el de Espa\u00f1a. All\u00ed nos hicieron una entrevista, lo cual es de agradecer que un medio tan importante a nivel nacional se interese por bandas de nuestro estilo. Algo que deber\u00edan de aprender nuestros paisanos.<\/em><\/p>\n<p><em>Lunes 19 de septiembre<\/em><\/p>\n<p><em>El lunes nos acercamos al peri\u00f3dico El Gr\u00e1fico, que al igual que La Raz\u00f3n, se trata de otro diario de nivel nacional y de gran tirada y despu\u00e9s nos acercamos a una zona residencial muy tranquila donde se encontraban las instalaciones de RADIO GRITA, donde hicimos una entrevista muy agradable para el programa \u201cEl Santo del Rock\u201d.<\/em><\/p>\n<p><em>El tr\u00e1fico de la ciudad en este d\u00eda se torn\u00f3 m\u00e1s agobiante, aunque no me pareci\u00f3 tan salvaje como nos contaban. Creo que la ciudad de El Cairo es mucho m\u00e1s ca\u00f3tica que M\u00e9xico D.F.<\/em><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/a1.sphotos.ak.fbcdn.net\/hphotos-ak-ash4\/313542_10150499890194848_160086484847_11529842_618040474_n.jpg\" alt=\"\" width=\"389\" height=\"218\" \/>Llegados a este punto pudimos comprobar que nuestra comida base se convirti\u00f3 en tacos y m\u00e1s tacos. De hecho hay que comentar que los favoritos de Javi fueron los \u201ccampechanos\u201d. Los consegu\u00edamos en puestos callejeros donde fuimos comprobando cuales nos gustaban m\u00e1s, y no nos parecieron tan picantes como pens\u00e1bamos.<\/em><\/p>\n<p><em>Martes 20 de septiembre<\/em><\/p>\n<p><em>El martes hicimos una entrevista y concierto ac\u00fastico en Radio UAM, donde debemos agradecer a Mari y a Carlos Daniel, dos fans de la banda, que nos dejaran sus guitarras ac\u00fasticas, ya que no pod\u00edamos traerlas desde Espa\u00f1a por cuestiones de espacio. Tocamos unos cuantos temas y la entrevista fue diferente a las dem\u00e1s. Nos hicieron recordar a nuestra Guadalajara natal y tuvimos que explicar de d\u00f3nde ven\u00eda el gentilicio de \u201calcarre\u00f1os\u201d.<\/em><\/p>\n<p><em>Tambi\u00e9n debo contar que por la ma\u00f1ana antes de ir a recoger las guitarras ac\u00fasticas, nos encontramos en el metro de Tasque\u00f1a un mercadillo de instrumentos musicales, bastante amplio, donde nos pusieron los dientes largos viendo la cantidad de guitarras, amplis y dem\u00e1s accesorios que pudimos ver.<\/em><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/a1.sphotos.ak.fbcdn.net\/hphotos-ak-ash4\/312043_10150499891059848_160086484847_11529849_1375156557_n.jpg\" alt=\"\" width=\"246\" height=\"327\" \/>A estas alturas de nuestra estancia en Ciudad de M\u00e9xico ya est\u00e1bamos acostumbrados perfectamente al transporte p\u00fablico donde no tuvimos ning\u00fan problema. Quiz\u00e1s alg\u00fan taxista que se quiso hacer el listillo, pero r\u00e1pidamente lo solucionamos.<\/em><\/p>\n<p><em>Ya por la noche fuimos a RADIO ALTERNO, donde nos trataron extremadamente bien, nada m\u00e1s llegar consiguieron una caja de cervezas y la velada se hizo muy agradable. Pusieron casi todo el disco y en una charla amistosa hablamos de muchas cosas sobre el grupo y la m\u00fasica en general.<\/em><\/p>\n<p><em>Mi\u00e9rcoles 21 de septiembre<\/em><\/p>\n<p><em>El mi\u00e9rcoles tuvimos que madrugar para ir a grabar a GARAJE TV, una aut\u00e9ntico garaje de vivienda unifamiliar donde tocamos varios temas y al finalizar hicimos una sesi\u00f3n de fotos, en la que ped\u00ed que me fotografiaran con un sombrero mexicano enorme&#8230; espero que pueda conseguir esas fotos! Y tambi\u00e9n grabamos entrevistas para un par de programas de radio. De ah\u00ed Pablo y Javi se fueron a llevar el equipo a casa y Jorge y yo fuimos hasta la otra punta de DF, que se dice pronto, para ir a Radio Faro de Oriente, donde tocamos un par de temas en ac\u00fastico y aparte hicimos una entrevista en v\u00eddeo para la asociaci\u00f3n MUCAC.<\/em><\/p>\n<p><em>Sin acabar el d\u00eda nos fuimos hasta la plaza de Bellas Artes donde quedamos con la gente de ROCKSTO una web dedicada obviamente al rock, donde nos grabaron en v\u00eddeo una entrevista en un bar mientras beb\u00edamos chelas (cervezas).<\/em><\/p>\n<p><em>Jueves 22 de septiembre<\/em><\/p>\n<p><em>El jueves se hac\u00eda nuestro \u00faltimo d\u00eda en Ciudad de M\u00e9xico y nos marchamos Pablo y yo a un parque a una entrevista para el magazine \u201cLos chavos son los chavos\u201d y por la noche fuimos a la sala Rock &amp; Road, una sala muy buena, hecha para moteros donde grabamos el programa HEAVY METAL ROCK SHOW.<\/em><\/p>\n<p><em>Nada m\u00e1s entrar lo primero que nos sorprendi\u00f3 fue el escenario, no era el m\u00e1s grande pero s\u00ed el mejor preparado en el que hemos estado. Estaba todo en su justa medida. Lleno de luces, humo y tres alturas donde en la parte m\u00e1s alta se ubicaba una bater\u00eda impresionante y muy buenos amplificadores. En la parte media es donde nos colocamos guitarristas y bajista y luego hab\u00eda otra altura m\u00e1s baja para acercarte m\u00e1s al p\u00fablico. Sin duda es el mejor escenario de sala en el que he tocado y debido al buen sonido, s\u00f3lo nos tuvimos que preocupar de darlo todo y as\u00ed fue.<\/em><\/p>\n<p><em>Tras terminar nos fuimos a la estaci\u00f3n de autobuses para viajar durante la noche a Guadalajara Jalisco. El autob\u00fas era muy c\u00f3modo y nos permiti\u00f3 dormir unas horas.<\/em><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"http:\/\/a5.sphotos.ak.fbcdn.net\/hphotos-ak-snc7\/313532_10150499891394848_160086484847_11529854_37202054_n.jpg\" alt=\"\" width=\"318\" height=\"211\" \/>Viernes 23 de septiembre<\/em><\/p>\n<p><em>Al llegar all\u00ed nos recogi\u00f3 nuestra fan Janny acompa\u00f1ada con el que ser\u00eda nuestro ch\u00f3fer en la ciudad tapat\u00eda, Paco. Nada m\u00e1s descargar nuestras cosas, nos dirigimos al peri\u00f3dico El Sol de Guadalajara para una entrevista. Ah\u00ed coincidimos con una banda de Le\u00f3n-Guanajuato, AUTTIST, gente muy agradable con los que compartimos nuestros dos d\u00edas en Guadalajara.<\/em><\/p>\n<p><em>De ah\u00ed nos fuimos todos a una entrevista en Radio 58, y despu\u00e9s una entrevista en v\u00eddeo para el colectivo KonFusi\u00f3n y m\u00e1s tarde ya bastante cansados al peri\u00f3dico Record, diario deportivo muy importante, tal como pueda ser aqu\u00ed el Marca o As, y que siempre incluye en sus l\u00edneas una propuesta musical.<\/em><\/p>\n<p><em>Al terminar toda esta agotadora gira de medios de hoy nos fuimos a la sala donde dar\u00edamos nuestro primer concierto en Guadalajara. Se trataba del MAINZ, un solar techado donde ten\u00edan una barra de bar a estilo chiringuito y donde desde el principio nos trataron genial. De hecho firmamos en una de las paredes del local. Luis, su encantador due\u00f1o, nos invit\u00f3 a cervezas hasta que llegaron los organizadores y un grupo de Guadalajara llamado Blue Room. El equipo que tra\u00edan no era nada bueno, de hecho la mesa de mezclas y un ampli de guitarra estallaron nada m\u00e1s enchufarlo y con el otro ampli era imposible de conseguir un buen sonido, as\u00ed que no pudimos tocar&#8230;<\/em><\/p>\n<p><em>S\u00e1bado 24 de septiembre<\/em><\/p>\n<p><em>Al d\u00eda siguiente fuimos al Tianguis Cultural de Guadalajara, es parecido al Chopo de DF pero con m\u00e1s variedad, te puedes encontrar casi cualquier cosa aunque no tenga que ver con el rock o el metal. All\u00ed coincidimos con el grupo madrile\u00f1o \u201cSTAFAS\u201d, donde Anono, el bater\u00eda, se acerc\u00f3 a nosotros a saludarnos. Un tipo muy simp\u00e1tico. A la hora de actuar all\u00ed tuvimos un problema parecido al de la noche anterior. El equipo lo tra\u00edan los grupos locales, y gracias a su \u201ccolaboraci\u00f3n\u201d, que nos relegaron a tocar en el \u00faltimo lugar a pesar de que estaba previsto que toc\u00e1ramos sobre las 12 de la ma\u00f1ana, s\u00f3lo nos ofrecieron un ampli de guitarra, cuando obviamente somos dos guitarristas, con lo que ya hartos de la organizaci\u00f3n, decidimos recoger nuestras cosas. Aprovechando la falta de equipo nos fuimos cerca a una entrevista en la radio M\u00e1xima FM. No os asust\u00e9is, aunque es una radio comercial no tiene nada que ver con la que hay en Espa\u00f1a.<\/em><\/p>\n<p><em>En esta ocasi\u00f3n tuvimos oportunidad de probar las t\u00edpicas tortas ahogadas de Guadalajara.<\/em><\/p>\n<p><em>Que son como bocadillos empapados en salsa de tomate. Muy ricas por cierto.<\/em><\/p>\n<p><em>Con estos acontecimientos, nuestras fans en la ciudad tapat\u00eda, que siempre estuvieron ah\u00ed apoy\u00e1ndonos, nos invitaron a una paella para que no tuvi\u00e9ramos nostalgia de nuestra tierra y nos regalaron unos momentos inolvidables. \u00a1\u00a1\u00a1Muchas gracias!!!<\/em><\/p>\n<p><em>Domingo 25 de septiembre<\/em><\/p>\n<p><em>Con mucha pena tuvimos que montarnos en el autob\u00fas que nos llevara a Ciudad de M\u00e9xico a recoger nuestras maletas y casi sin descansar, irnos al aeropuerto para volver a casa.<\/em><\/p>\n<p><em>Nos fuimos con la sensaci\u00f3n de que hemos hecho algo importante en M\u00e9xico, hemos plantado una semilla que creemos firmemente que crecer\u00e1 con el tiempo y sobre todo ante nuestra casi inminente grabaci\u00f3n del segundo disco de la banda, el cual esperamos que nos haga m\u00e1s conocidos all\u00e1.<\/em><\/p>\n<p><em>Fueron d\u00edas intensos, de mucho trabajo y donde pudimos disfrutar de la enorme amabilidad y hospitalidad del pueblo mexicano. Se nos ha querido mucho y nosotros lo agradecemos con todo coraz\u00f3n. \u00a1Se os quiere! \u00a1Viva M\u00e9xico! \u00a1Hasta pronto!!!<\/em><\/p>\n<p><em>Sergio Necroberus<\/em><\/p>\n<p><em>Guadalajara, Octubre de 2011<\/em><\/p>\n<p>Muchas gracias de parte de todoheavymetal.com a NECROBERUS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sergio, cantante y guitarra de NECROBERUS, se pone en contacto con nosotros y nos manda el diario de la gira que han realizado por tierras mexicanas durante el mes de septiembre, presentando su disco G\u00e9nesis y poco antes de su inminente entrada en el estudio para registrar su segundo disco. Todo un documento de lo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[6458,6460,4214,6,6459],"class_list":["post-7993","post","type-post","status-publish","format-standard","hentry","category-noticias-del-mes","tag-diario-gira-mexicana-necroberus","tag-gira-mexicana-necroberus","tag-necroberus","tag-noticias-heavy-metal","tag-noticias-necroberus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIARIO DE LA GIRA MEXICANA DE NECROBERUS - HEAVY METAL - NOTICIAS HEAVY METAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIARIO DE LA GIRA MEXICANA DE NECROBERUS - HEAVY METAL - NOTICIAS HEAVY METAL\" \/>\n<meta property=\"og:description\" content=\"Sergio, cantante y guitarra de NECROBERUS, se pone en contacto con nosotros y nos manda el diario de la gira que han realizado por tierras mexicanas durante el mes de septiembre, presentando su disco G\u00e9nesis y poco antes de su inminente entrada en el estudio para registrar su segundo disco. Todo un documento de lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus\" \/>\n<meta property=\"og:site_name\" content=\"HEAVY METAL - NOTICIAS HEAVY METAL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/todoheavymetal\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-24T17:07:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/a7.sphotos.ak.fbcdn.net\/hphotos-ak-ash4\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg\" \/>\n<meta name=\"author\" content=\"Javi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@todoheavymetal\" \/>\n<meta name=\"twitter:site\" content=\"@todoheavymetal\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus\"},\"author\":{\"name\":\"Javi\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/#\\\/schema\\\/person\\\/aa098e79c44b992ec2357a75883ed217\"},\"headline\":\"DIARIO DE LA GIRA MEXICANA DE NECROBERUS\",\"datePublished\":\"2011-10-24T17:07:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus\"},\"wordCount\":2113,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/a7.sphotos.ak.fbcdn.net\\\/hphotos-ak-ash4\\\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg\",\"keywords\":[\"diario gira mexicana necroberus\",\"gira mexicana necroberus\",\"necroberus\",\"noticias heavy metal\",\"noticias necroberus\"],\"articleSection\":[\"Noticias del mes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus\",\"url\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus\",\"name\":\"DIARIO DE LA GIRA MEXICANA DE NECROBERUS - HEAVY METAL - NOTICIAS HEAVY METAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/a7.sphotos.ak.fbcdn.net\\\/hphotos-ak-ash4\\\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg\",\"datePublished\":\"2011-10-24T17:07:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/#\\\/schema\\\/person\\\/aa098e79c44b992ec2357a75883ed217\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus#primaryimage\",\"url\":\"http:\\\/\\\/a7.sphotos.ak.fbcdn.net\\\/hphotos-ak-ash4\\\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg\",\"contentUrl\":\"http:\\\/\\\/a7.sphotos.ak.fbcdn.net\\\/hphotos-ak-ash4\\\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/diario-de-la-gira-mexicana-de-necroberus#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.todoheavymetal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIARIO DE LA GIRA MEXICANA DE NECROBERUS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/#website\",\"url\":\"https:\\\/\\\/www.todoheavymetal.com\\\/\",\"name\":\"todoheavymetal.com\",\"description\":\"heavy metal - noticias heavy metal - todoheavymetal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todoheavymetal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/#\\\/schema\\\/person\\\/aa098e79c44b992ec2357a75883ed217\",\"name\":\"Javi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad9699b1143ed4017d23ce58fa9d83e0375bd1368122b157550ad77cd28bdfdf?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad9699b1143ed4017d23ce58fa9d83e0375bd1368122b157550ad77cd28bdfdf?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad9699b1143ed4017d23ce58fa9d83e0375bd1368122b157550ad77cd28bdfdf?s=96&d=monsterid&r=g\",\"caption\":\"Javi\"},\"url\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/author\\\/javipelos\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIARIO DE LA GIRA MEXICANA DE NECROBERUS - HEAVY METAL - NOTICIAS HEAVY METAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus","og_locale":"es_ES","og_type":"article","og_title":"DIARIO DE LA GIRA MEXICANA DE NECROBERUS - HEAVY METAL - NOTICIAS HEAVY METAL","og_description":"Sergio, cantante y guitarra de NECROBERUS, se pone en contacto con nosotros y nos manda el diario de la gira que han realizado por tierras mexicanas durante el mes de septiembre, presentando su disco G\u00e9nesis y poco antes de su inminente entrada en el estudio para registrar su segundo disco. Todo un documento de lo [&hellip;]","og_url":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus","og_site_name":"HEAVY METAL - NOTICIAS HEAVY METAL","article_publisher":"https:\/\/www.facebook.com\/todoheavymetal\/","article_published_time":"2011-10-24T17:07:16+00:00","og_image":[{"url":"http:\/\/a7.sphotos.ak.fbcdn.net\/hphotos-ak-ash4\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg","type":"","width":"","height":""}],"author":"Javi","twitter_card":"summary_large_image","twitter_creator":"@todoheavymetal","twitter_site":"@todoheavymetal","twitter_misc":{"Escrito por":"Javi","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus#article","isPartOf":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus"},"author":{"name":"Javi","@id":"https:\/\/www.todoheavymetal.com\/#\/schema\/person\/aa098e79c44b992ec2357a75883ed217"},"headline":"DIARIO DE LA GIRA MEXICANA DE NECROBERUS","datePublished":"2011-10-24T17:07:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus"},"wordCount":2113,"commentCount":1,"image":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus#primaryimage"},"thumbnailUrl":"http:\/\/a7.sphotos.ak.fbcdn.net\/hphotos-ak-ash4\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg","keywords":["diario gira mexicana necroberus","gira mexicana necroberus","necroberus","noticias heavy metal","noticias necroberus"],"articleSection":["Noticias del mes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus","url":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus","name":"DIARIO DE LA GIRA MEXICANA DE NECROBERUS - HEAVY METAL - NOTICIAS HEAVY METAL","isPartOf":{"@id":"https:\/\/www.todoheavymetal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus#primaryimage"},"image":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus#primaryimage"},"thumbnailUrl":"http:\/\/a7.sphotos.ak.fbcdn.net\/hphotos-ak-ash4\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg","datePublished":"2011-10-24T17:07:16+00:00","author":{"@id":"https:\/\/www.todoheavymetal.com\/#\/schema\/person\/aa098e79c44b992ec2357a75883ed217"},"breadcrumb":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus#primaryimage","url":"http:\/\/a7.sphotos.ak.fbcdn.net\/hphotos-ak-ash4\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg","contentUrl":"http:\/\/a7.sphotos.ak.fbcdn.net\/hphotos-ak-ash4\/320808_10150435645999848_160086484847_11130661_799621543_n.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/diario-de-la-gira-mexicana-de-necroberus#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.todoheavymetal.com\/"},{"@type":"ListItem","position":2,"name":"DIARIO DE LA GIRA MEXICANA DE NECROBERUS"}]},{"@type":"WebSite","@id":"https:\/\/www.todoheavymetal.com\/#website","url":"https:\/\/www.todoheavymetal.com\/","name":"todoheavymetal.com","description":"heavy metal - noticias heavy metal - todoheavymetal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todoheavymetal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.todoheavymetal.com\/#\/schema\/person\/aa098e79c44b992ec2357a75883ed217","name":"Javi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad9699b1143ed4017d23ce58fa9d83e0375bd1368122b157550ad77cd28bdfdf?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad9699b1143ed4017d23ce58fa9d83e0375bd1368122b157550ad77cd28bdfdf?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad9699b1143ed4017d23ce58fa9d83e0375bd1368122b157550ad77cd28bdfdf?s=96&d=monsterid&r=g","caption":"Javi"},"url":"https:\/\/www.todoheavymetal.com\/index.php\/author\/javipelos"}]}},"_links":{"self":[{"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/posts\/7993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/comments?post=7993"}],"version-history":[{"count":1,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/posts\/7993\/revisions"}],"predecessor-version":[{"id":7994,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/posts\/7993\/revisions\/7994"}],"wp:attachment":[{"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/media?parent=7993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/categories?post=7993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/tags?post=7993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}