{"id":13341,"date":"2012-07-10T18:00:50","date_gmt":"2012-07-10T16:00:50","guid":{"rendered":"http:\/\/www.todoheavymetal.com\/?p=13341"},"modified":"2012-07-10T23:13:00","modified_gmt":"2012-07-10T21:13:00","slug":"entrevista-a-juanjo-ruiz-bateria-de-siracida","status":"publish","type":"post","link":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida","title":{"rendered":"ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/4.bp.blogspot.com\/_RpfwmfKwJwg\/TQXq77MVRBI\/AAAAAAAAAGY\/zusAphveUWU\/s1600\/disco.jpg\" alt=\"\" width=\"300\" height=\"300\" \/>todoheavymetal se puso en contacto con la emergente banda murciana de power metal mel\u00f3dico, SIR\u00c1CIDA, para que nos contaran de primera mano c\u00f3mo est\u00e1 siendo la aceptaci\u00f3n de su primer trabajo <em>Del Coraz\u00f3n al Alma<\/em> y nos contaran las \u00faltimas noticias referentes a la banda. A continuaci\u00f3n os ponemos la interesante entrevista mantenida con Juanjo Ruiz, bater\u00eda de la banda.<\/p>\n<p><strong>Un saludo y enhorabuena por vuestro excelente \u00e1lbum <em>Del Coraz\u00f3n al Alma<\/em> y por la gira asociada que est\u00e1 llevando a la banda por buena parte de la geograf\u00eda espa\u00f1ola. Lo primero pediros perd\u00f3n por la casi segura poco originalidad de las preguntas, ya que seguramente la mayor\u00eda de ellas os habr\u00e1n sido preguntadas en infinidad de ocasiones.<\/strong><\/p>\n<p><strong>-Empezamos por lo m\u00e1s reciente. Triste noticia, sin duda, la marcha del grupo de Daniel Ort\u00edn vuestro bajista de toda la vida y amigo personal. Supongo que fue un aut\u00e9ntico trauma para el grupo el dejar de contar con una persona tan cualificada y tan querida como \u00e9l. \u00bfPodr\u00edais contar a nuestros seguidores y sobre todo a los fans del grupo, cu\u00e1les fueron los motivos de dicha separaci\u00f3n? \u00bfOs hab\u00e9is visto obligados a modificar alguna fecha de la gira debido a esto?<\/strong><\/p>\n<p>Todo ha sido muy sorprendente para nosotros, supongo que cuando decidimos avanzar como grupo y tomar la decisi\u00f3n de convertirnos en una banda a nivel nacional se adquiere un compromiso mas serio y hay que realizar algunos sacrificios, sobretodo a nivel personal, hay momentos en los que hay que eligir y \u00e9l ha elegido su camino, decisi\u00f3n que respetamos y aceptamos, solo podemos decir te echaremos de menos hermano.<\/p>\n<p>En cuanto a la gira no ha variado nada, continuaremos con ella y realizaremos todas las fechas. Estamos deseando encontrarnos con los fans y disfrutar con ellos.<\/p>\n<p><strong>-Siguiendo con el tema del nuevo bajista, \u00bfactualmente ten\u00e9is el hueco bien cubierto con la uni\u00f3n al grupo de <em>Roger Maccary (LORYEN, TREEMAROMS)<\/em>, m\u00fasico bien conocido por la banda y con suficiente experiencia, o es algo provisional hasta que encontr\u00e9is a otro sustituto?<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"http:\/\/3.bp.blogspot.com\/_RpfwmfKwJwg\/TQXnSaXS0UI\/AAAAAAAAAFs\/HrpL7walCp0\/S1600-R\/juanjoruiz.gif\" alt=\"\" width=\"167\" height=\"309\" \/>No sabemos como va a terminara todo esto, Roger se entero de la noticia y nos llam\u00f3, se ofreci\u00f3 para ayudarnos y poder continuar la gira, ya que Daniel nos abandon\u00f3 a cinco d\u00edas de la actuaci\u00f3n en Santander, el concierto se realiz\u00f3 y tuvimos muy buenas vibraciones en el escenario, as\u00ed que nos propuso continuar hasta el final de la gira, despu\u00e9s ya veremos, de momento ya se ha preparado su pintura para los conciertos.<\/p>\n<p><strong>-Cambiando de tema, en cuanto a los or\u00edgenes del grupo, aunque \u00fanicamente teng\u00e1is unas maquetas, un EP del 2008 llamado <em>No M\u00e1s Mentiras <\/em>y el ya citado <em>Del Coraz\u00f3n al Alma<\/em> del a\u00f1o 2012, se puede decir que sois una banda con una dilatada experiencia. \u00bfPodr\u00edais comentarnos c\u00f3mo surge la idea de formar SIR\u00c1CIDA? \u00bfEn qu\u00e9 han cambiado vuestras vidas desde entonces?<\/strong><\/p>\n<p>Pues como todos los grupo empiezan, nos encantaba el heavy metal y pensamos, \u00bfporqu\u00e9 no hacemos un grupo?. Nunca pensamos que aguantar\u00edamos tanto, pero aqu\u00ed estamos. Aguantar es bastante dif\u00edcil, la gente evoluciona en su vida, adquiere responsabilidades, se casa, tiene hijos, trabaja y dem\u00e1s, nosotros hemos hecho todo eso y adem\u00e1s seguimos con Sir\u00e1cida, el secreto es nuestra amistad, somos amigos y despu\u00e9s m\u00fasicos y eso hace que nos perdonemos cosas que quiz\u00e1s en otro grupos serian causa de separaci\u00f3n.<\/p>\n<p><strong>-En sus comienzos el grupo estaba m\u00e1s enfocado al power metal \u00e9pico, con todo lo que lleva asociado de l\u00edrica, m\u00fasica e imagen. \u00bfPor qu\u00e9 ese cambio musical? \u00bfC\u00f3mo os definir\u00edais musicalmente ahora mismo?, o en otras palabras, \u00bfQu\u00e9 aporta SIR\u00c1CIDA al panorama metalero actual en Espa\u00f1a?<\/strong><\/p>\n<p>Nos estamos haciendo viejos\u2026 No, en serio, es una evoluci\u00f3n natural, ll\u00e1malo madurez, antes lo bas\u00e1bamos todo mas en la velocidad, intent\u00e1bamos imitar lo que escuch\u00e1bamos. Con los a\u00f1os hemos ido encontrando nuestro estilo, ahora se podr\u00eda decir que sonamos a Sir\u00e1cida y eso es lo importante, tener personalidad y saber que es lo queremos hacer.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/3.bp.blogspot.com\/_RpfwmfKwJwg\/TQXn1qJ5YbI\/AAAAAAAAAF0\/X0cRHVeMlp4\/S1600-R\/manuelzaragoza.gif\" alt=\"\" width=\"167\" height=\"309\" \/><strong>-Hablando de vuestro \u00faltimo trabajo <em>Del Coraz\u00f3n al Alma<\/em>, del que ya ha pasado m\u00e1s de a\u00f1o y medio desde su salida y que personalmente creo ha sido y seguir\u00e1 siendo una muy grata sorpresa por la frescura y la calidad que ha aportado al metal hispano. \u00bfFue f\u00e1cil para el grupo el dar el paso adelante y meteros a grabar el disco?, \u00bfQu\u00e9 buscabais cuando decidisteis sacar al mercado <em>Del Coraz\u00f3n al Alma<\/em>?<\/strong><\/p>\n<p>Nunca es f\u00e1cil afrontar un proyecto como este, dar a conocer un nuevo grupo, con todo lo que eso supone y sin un respaldo que te pueda hacer abrirte camino, adem\u00e1s una de las consecuencias de tomarte este negocio mas en serio es que tal vez todos los que te acompa\u00f1en no lo vean igual o no est\u00e9n dispuestos a seguirte, como nos ha pasado con nuestro bajista, aun as\u00ed no fue dif\u00edcil tomar esa decisi\u00f3n ya que esto es lo queremos hacer, nuestra pasi\u00f3n y tal vez sea nuestro momento, el trabajo esta ah\u00ed y estamos deseando continuar en la carretera, grabar el pr\u00f3ximo disco y seguir tocando heavy metal hasta que se apague el sol.<\/p>\n<p><strong>-Que nosotros sepamos no ha salido ning\u00fan videoclip como apoyo promocional para el disco. \u00bfA qu\u00e9 se ha debido?<\/strong><\/p>\n<p>Es debido \u00fanica y exclusivamente a la pasta, no quer\u00edamos hacer nada que no nos gustara. Vamos a realizar un videoclip de una canci\u00f3n in\u00e9dita que se va a incluir en la banda sonora de un corto llamado el ultimo caballero y seguramente el pr\u00f3ximo disco, que saldr\u00e1 a principios de a\u00f1o, tambi\u00e9n tendr\u00e1 como apoyo de la promoci\u00f3n un videoclip.<br \/>\nDe todas formas el disco incluye un documental de c\u00f3mo se grab\u00f3, solo tienes que meterlo en tu PC y lo veras, pero no es lo mismo.<\/p>\n<p><strong>-En el plano compositivo los temas son muy variados. \u00bfCu\u00e1les son las <\/strong><strong>actuales fuentes de inspiraci\u00f3n del grupo a la hora de componer? \u00bfC\u00f3mo es el proceso compositivo normal de la banda? <\/strong><\/p>\n<p>Nosotros bebemos de todo y muy variado y si es una fuente de la que brote cerveza mejor que mejor \u2026( risas ). No ahora en serio, el grupo es una mezcla de gustos musicales, desde la NWOBHM y el thrash metal de los 80 hasta el metal progresivo que se escucha en la actualidad, pasando por el hard rock y el Glam y por supuesto el power metal de los 90, quiz\u00e1 la m\u00fasica que m\u00e1s nos ha marcado, por lo que al poner todos nuestro granito de arena a la hora de componer melod\u00edas y estructuras y aportar matices, es muy dif\u00edcil describir la forma de componer del grupo, te dir\u00e9 que hasta que no se nos ponen los pelos de punta con un tema no pensamos en terminarlo, por lo que se podr\u00eda decir que somos un poco lentos a la hora de componer y si encima nos pones una fuente de cerveza\u2026( Risas ).<\/p>\n<p><strong>-Si pudierais empezar de cero, \u00bfQu\u00e9 es lo que cambiar\u00edas de \u00e9ste trabajo? Y al contrario, \u00bfDe qu\u00e9 es de lo que os sent\u00eds m\u00e1s orgullosos?<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"http:\/\/3.bp.blogspot.com\/_RpfwmfKwJwg\/TQXmz84wVSI\/AAAAAAAAAFk\/7hsMSJ04Oek\/S1600-R\/victorlopez.gif\" alt=\"\" width=\"167\" height=\"309\" \/>Cambiar\u00eda el haber escuchado a determinada gente que nos prometieron muchas cosas y despu\u00e9s no se ha cumplido nada, no ten\u00edamos muy claro como funcionaba este negocio, dos a\u00f1os despu\u00e9s hemos tomado las riendas de nuestro destino, si eso lo hubi\u00e9ramos hecho antes no hubi\u00e9ramos perdido todo un a\u00f1o, casi nos cuesta el grupo, por lo que de lo que mas orgullosos nos sentimos es de haber ca\u00eddo y habernos levantado de nuevo.<\/p>\n<p><strong>-\u00bfC\u00f3mo hab\u00e9is encontrado la respuesta de la gente a vuestro \u00e1lbum tanto en ventas como en directo? \u00bfCu\u00e1les son los temas que est\u00e1n teniendo m\u00e1s aceptaci\u00f3n? (Yo me quedo con todo el disco, pero si tuviera que elegir me quedar\u00eda con la energ\u00eda de \u201cGuijarros\u201d y \u201cEsparta\u201d y con \u201cAve F\u00e9nix\u201d por sus arreglos m\u00e1s progresivos)<\/strong><\/p>\n<p>En cuanto a ventas se han vendido unas 400 copias, de las cuales no hemos cobrado nada ya que nuestra anterior compa\u00f1\u00eda todav\u00eda no nos ha pagado lo que nos debe, a eso debemos sumar las copias que hemos ido dando con la entrada en la gira y que continuaremos dando hasta el final de esta.<\/p>\n<p>Y los temas mas pedidos en directo son \u201cguijarros\u201d por supuesto y \u201chombro con hombro\u201d y hay un tema que nos ha sorprendido por su gran aceptaci\u00f3n, ya que es m\u00e1s complicado de escuchar aunque en directo en una autentica bomba, de lo cual no est\u00e1bamos muy seguros e incluso estuvimos apunto de no incluirla en el disco, se trata de \u201cla pasi\u00f3n\u201d pero a la gente le ha encantado y es un tema que nunca hemos dejado de tocar en directo.<\/p>\n<p><strong>-El pasado 27 y 28 de abril estuvisteis tocando en directo en Madrid, concierto al que tristemente no pudimos acudir, cosa que esperamos corregir a la pr\u00f3xima oportunidad. Siendo Madrid uno de los te\u00f3ricos centros de referencia dentro del heavy metal, \u00bfC\u00f3mo describir\u00edais la acogida por parte de la gente? \u00bfCu\u00e1l es el concierto que m\u00e1s os ha gustado hasta ahora y donde hab\u00e9is estado m\u00e1s a gusto por la raz\u00f3n que sea?<\/strong><\/p>\n<p>Sin duda por ahora el concierto de la sala Excalibur en Madrid, por todo lo que conllev\u00f3, ir por fin a Madrid a presentar nuestro trabajo para los medios nacionales, por cierto te pusimos falta\u2026 ( risas ), el lugar, una de las salas m\u00edticas del heavy metal nacional, un par de semanas antes de que cerrara sus puertas, para nosotros fue algo muy especial. Adem\u00e1s, no esper\u00e1bamos que se desplazara gente al lugar que tuviera nuestro disco y disfrutara tanto de nuestra m\u00fasica, no te voy a enga\u00f1ar, no eran mas de 35 personas, ya que nos coincidi\u00f3 con el puente, pero lo pasamos en grande y estamos deseando volver y esta vez no te perdonaremos la falta\u2026 ( risas ).<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/2.bp.blogspot.com\/_RpfwmfKwJwg\/TQXoZYh19RI\/AAAAAAAAAF8\/BbMt4AxhUfg\/S1600-R\/rubennicolas.gif\" alt=\"\" width=\"167\" height=\"309\" \/>-En los \u00faltimos tiempos, m\u00e1s de un m\u00fasico nos ha comentado que el tema de tocar en festivales para bandas como vosotros y muchas m\u00e1s est\u00e1 bastante jodido si no tienes ciertos contactos \u00bfc\u00f3mo veis la posibilidad de entrar en el cartel de alg\u00fan festival veraniego?<\/strong><\/p>\n<p>No te voy a enga\u00f1ar este verano estamos a cero, estamos intentando meter la cabeza para el a\u00f1o que viene. Es la asignatura pendiente del grupo, ya que un festival es el sitio perfecto para promocionar grupos nuevos y que podamos tocar en un escenario grande, con bastante p\u00fablico y sentirnos por un momento importantes.<\/p>\n<p>No se los contactos que hay que tener, nosotros no tenemos ninguno, solo nuestro sello y lo que nos movemos nosotros, pero te aseguro que lo vamos a seguir intentando.<\/p>\n<p><strong>-Pregunta inevitable que seguramente estar\u00e9is hartos de contestar: \u00bfCu\u00e1les han sido y qu\u00e9 bandas actuales son las que m\u00e1s pueden estar influenciando en vuestra m\u00fasica?<\/strong><\/p>\n<p>Pues nuestra m\u00fasica esta influenciada por grupos como Symphony X y Avalanch sobretodo, en la actualidad tampoco nos fijamos demasiado en lo que hacen otras formaciones, sino que como te he comentado anteriormente buscamos algo m\u00e1s personal. Tambi\u00e9n escuchamos bandas sonoras como <em>Conan el b\u00e1rbaro<\/em> o <em>Braveheart<\/em> autenticas obras de arte imposibles de superar.<\/p>\n<p><strong>-Cambiando de tema, muchos grupos est\u00e1 actualmente optando por la edici\u00f3n digital de sus trabajos como v\u00eda para llegar al m\u00e1ximo n\u00famero de gente posible y darse as\u00ed a conocer de una forma lo m\u00e1s extensiva posible. Adem\u00e1s, hoy en d\u00eda es muy dif\u00edcil vivir de la m\u00fasica en cuanto a venta de discos e incluso en muchos casos afluencia a conciertos. Aunque actualmente form\u00e1is parte del sello discogr\u00e1fico \u201cGothic Rec &amp; Productions\u201d que a buen seguro os estar\u00e1 ayudando a distribuir el CD y a concertar fechas para la gira, inicialmente supongo que tendr\u00edais ese mismo tipo de problemas. La pregunta es, \u00bfOs planteasteis en su momento en poner a disposici\u00f3n de la gente vuestro trabajo en formato digital gratuito? Adem\u00e1s, en relaci\u00f3n con lo anterior \u00bfPodr\u00edais decirnos c\u00f3mo veis y qu\u00e9 esper\u00e1is del panorama actual de la m\u00fasica heavy en Espa\u00f1a?<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"http:\/\/4.bp.blogspot.com\/_RpfwmfKwJwg\/TQXpN29RRzI\/AAAAAAAAAGM\/o176wuKAZGw\/S1600-R\/jaimesamper.gif\" alt=\"\" width=\"167\" height=\"309\" \/>A la primera pregunta la respuesta es no, si me parece bien colgar algunos temas del disco para promocionarlo, pero todo el material no me parece justo. Para mi es menospreciar a los m\u00fasicos que trabajan muy duro para preparar un material en el que adem\u00e1s de tiempo han volcado ilusi\u00f3n, creatividad y fuerza. Todos queremos que haya grupos de heavy metal, pero nadie quiere apoyar a esos grupos. Antes probablemente ten\u00edamos la escusa de que todo el dinero de los discos se lo llevaban los jefes de las discogr\u00e1ficas, pero ahora, casi todos los grupos de metal son autoproducidos. Qu\u00e9 mejor que apoyar a los grupos que est\u00e1n luchan para que la escena de nuestra m\u00fasica no desaparezca.<\/p>\n<p>Siempre me ha parecido que los fans del heavy metal somos los mas fieles y los mas sinceros, los mas cr\u00edticos con nuestros grupos y los mas agradecidos, pero como te he comentado antes hay que apoyar la escena y sentirnos orgullosos de lo que somos, estar con nuestros grupos, que est\u00e1n ah\u00ed dando su tiempo, dinero e ilusi\u00f3n. No hay nada mas grande en la m\u00fasica que un concierto de heavy metal, no dejemos que esto acabe jam\u00e1s.<\/p>\n<p><strong>-Supongo que ya tendr\u00e9is material nuevo preparado y que lo estar\u00e9is presentando o pensar\u00e9is presentarlo en directo en vuestros pr\u00f3ximos conciertos. \u00bfNos pod\u00e9is adelantar algo de informaci\u00f3n referente a vuestro pr\u00f3ximo trabajo?<\/strong><\/p>\n<p>Si te lo dijera tendr\u00eda que matarte\u2026 ( risas ). No, en serio, ya estamos presentando dos temas del nuevo material en directo y est\u00e1n teniendo bastante aceptaci\u00f3n. Seguramente repetiremos esquema con una intro y una outro, adem\u00e1s de ser algo mas progresivo que el anterior, sin abandonar la senda del heavy metal mel\u00f3dico. Los temas ser\u00e1n algo m\u00e1s cortos aunque no descartamos incluir alg\u00fan tema de desarrollo. En definitiva, que la gente se lo compre y vaya a los conciertos y as\u00ed saldr\u00e1n de dudas.<\/p>\n<p><strong>-En cuanto al directo del grupo, sol\u00e9is recibir muy buenas cr\u00edticas en cuanto a actitud, aptitud y puesta en escena, con esos maquillajes tan ochenteros que particularmente me recuerda a los americanos Crimson Glory. \u00bfA qu\u00e9 se debe el tema del maquillaje y qu\u00e9 puede esperar un seguidor que acuda por primera vez a uno de vuestros conciertos?<\/strong><\/p>\n<p>Los maquillajes son parte de la est\u00e9tica del grupo, es algo que comenzamos ha hacer para acompa\u00f1ar la tem\u00e1tica guerrera de las canciones que compon\u00edamos anteriormente. Sac\u00e1bamos espadas, antorchas y dem\u00e1s, todo eso ya qued\u00f3 en el pasado, pero los maquillajes siguen acompa\u00f1\u00e1ndonos, son como nuestras pinturas de guerra antes de salir al escenario a darlo todo. Adem\u00e1s, el proceso de pintarnos es un autentico ritual donde todos nos juntamos antes de tocar, nos tomamos algo juntos y nos preparamos para dar la descarga de heavy metal que se merece alguien que paga una entrada para vernos.<\/p>\n<p><strong>-Y por fin, la \u00faltima pregunta: \u00bfTen\u00e9is la gira \u201cDel Coraz\u00f3n al Alma Tour 2012\u201d ya cerrada u os quedan por confirmar a\u00fan m\u00e1s fechas antes de embarcaros en la grabaci\u00f3n de vuestro pr\u00f3ximo trabajo?<\/strong><\/p>\n<p>Pues las fechas que tenemos est\u00e1n cerradas pero no descartamos a\u00f1adir mas, ya que queremos tocar en todos lo lugares donde se pueda y nos quieran escuchar. Estamos a la espera de que nos confirmen un par de fechas mas, adem\u00e1s de las ya conocidas de el 25 de Agosto en Hell\u00edn en la sala Black Rose, el 7 de Septiembre concierto ac\u00fastico en el Ladrillo en Murcia, el 08 de Septiembre en la sala Rojas en Murcia, el 15 de Septiembre en la sala S\u00faper music en C\u00e1diz y el 15 de Diciembre taloneando a Iron Savior en la sala la Matriz Creativa. Ese ser\u00e1 en concierto de fin de gira. Hay un par de fechas en octubre que todav\u00eda no se han cerrado, de las que te dar\u00e9 cuenta cuando est\u00e9n fijadas.<\/p>\n<p><strong>-Por nuestra parte esto ha sido todo, \u00bfOs gustar\u00eda a\u00f1adir algo m\u00e1s para los lectores de www.todoheavymetal.com?<\/strong><\/p>\n<p>Que sigan escuchando heavy metal, que sigan siendo como son, que nadie les diga como tienen que ser y como deben vivir sus vidas pues de lo \u00fanico que nos tenemos que avergonzar los heavys es de la envidia que le damos a los dem\u00e1s, y un saludo de Sir\u00e1cida para todos los metaleros que lean estas l\u00edneas. Larga vida al heavy metal!!!.<\/p>\n<p><strong>Pues eso, desde todoheavymetal.com quisi\u00e9ramos aconsejar a la gente que nos lee que no se pierda vuestros conciertos, y a SIR\u00c1CIDA el habernos atendido tan amablemente adem\u00e1s de desearos sinceramente toda la suerte, el \u00e9xito y la libertad que sin duda os merec\u00e9is.<\/strong><\/p>\n<p>Darte las gracias a ti por tu profesionalidad y por esta oportunidad de darnos a conocer un poquito mas a nuestros fans, muchas gracias. Sir\u00e1cida os desea lo mejor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>todoheavymetal se puso en contacto con la emergente banda murciana de power metal mel\u00f3dico, SIR\u00c1CIDA, para que nos contaran de primera mano c\u00f3mo est\u00e1 siendo la aceptaci\u00f3n de su primer trabajo Del Coraz\u00f3n al Alma y nos contaran las \u00faltimas noticias referentes a la banda. A continuaci\u00f3n os ponemos la interesante entrevista mantenida con Juanjo [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2548,8],"tags":[10466,10467,10468],"class_list":["post-13341","post","type-post","status-publish","format-standard","hentry","category-entrevistas","category-noticias-del-mes","tag-entrevista-a-juanjo-ruiz-bateria-de-siracida-todoheavymetal-com","tag-entrevista-a-siracida-todoheavymetal-com","tag-siracida-todoheavymetal-com"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA - HEAVY METAL - NOTICIAS HEAVY METAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA - HEAVY METAL - NOTICIAS HEAVY METAL\" \/>\n<meta property=\"og:description\" content=\"todoheavymetal se puso en contacto con la emergente banda murciana de power metal mel\u00f3dico, SIR\u00c1CIDA, para que nos contaran de primera mano c\u00f3mo est\u00e1 siendo la aceptaci\u00f3n de su primer trabajo Del Coraz\u00f3n al Alma y nos contaran las \u00faltimas noticias referentes a la banda. A continuaci\u00f3n os ponemos la interesante entrevista mantenida con Juanjo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida\" \/>\n<meta property=\"og:site_name\" content=\"HEAVY METAL - NOTICIAS HEAVY METAL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/todoheavymetal\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-10T16:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-07-10T21:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/4.bp.blogspot.com\/_RpfwmfKwJwg\/TQXq77MVRBI\/AAAAAAAAAGY\/zusAphveUWU\/s1600\/disco.jpg\" \/>\n<meta name=\"author\" content=\"marciaaaaal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@todoheavymetal\" \/>\n<meta name=\"twitter:site\" content=\"@todoheavymetal\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marciaaaaal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida\"},\"author\":{\"name\":\"marciaaaaal\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/#\\\/schema\\\/person\\\/e3170256584bfef679ff987358c5cabc\"},\"headline\":\"ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA\",\"datePublished\":\"2012-07-10T16:00:50+00:00\",\"dateModified\":\"2012-07-10T21:13:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida\"},\"wordCount\":3005,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/4.bp.blogspot.com\\\/_RpfwmfKwJwg\\\/TQXq77MVRBI\\\/AAAAAAAAAGY\\\/zusAphveUWU\\\/s1600\\\/disco.jpg\",\"keywords\":[\"ENTREVISTA A JUANJO RUIZ BATER\u00cdA DE SIR\u00c1CIDA todoheavymetal.com\",\"ENTREVISTA A SIR\u00c1CIDA todoheavymetal.com\",\"sir\u00e1cida todoheavymetal.com\"],\"articleSection\":[\"ENTREVISTAS\",\"Noticias del mes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida\",\"url\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida\",\"name\":\"ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA - HEAVY METAL - NOTICIAS HEAVY METAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/4.bp.blogspot.com\\\/_RpfwmfKwJwg\\\/TQXq77MVRBI\\\/AAAAAAAAAGY\\\/zusAphveUWU\\\/s1600\\\/disco.jpg\",\"datePublished\":\"2012-07-10T16:00:50+00:00\",\"dateModified\":\"2012-07-10T21:13:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/#\\\/schema\\\/person\\\/e3170256584bfef679ff987358c5cabc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida#primaryimage\",\"url\":\"http:\\\/\\\/4.bp.blogspot.com\\\/_RpfwmfKwJwg\\\/TQXq77MVRBI\\\/AAAAAAAAAGY\\\/zusAphveUWU\\\/s1600\\\/disco.jpg\",\"contentUrl\":\"http:\\\/\\\/4.bp.blogspot.com\\\/_RpfwmfKwJwg\\\/TQXq77MVRBI\\\/AAAAAAAAAGY\\\/zusAphveUWU\\\/s1600\\\/disco.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/noticias-del-mes\\\/entrevista-a-juanjo-ruiz-bateria-de-siracida#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.todoheavymetal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/#website\",\"url\":\"https:\\\/\\\/www.todoheavymetal.com\\\/\",\"name\":\"todoheavymetal.com\",\"description\":\"heavy metal - noticias heavy metal - todoheavymetal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todoheavymetal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.todoheavymetal.com\\\/#\\\/schema\\\/person\\\/e3170256584bfef679ff987358c5cabc\",\"name\":\"marciaaaaal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57d360e5d1ff29399da35b7b52fc5e6d6b9219477d69870fa99c6af65ed94dee?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57d360e5d1ff29399da35b7b52fc5e6d6b9219477d69870fa99c6af65ed94dee?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57d360e5d1ff29399da35b7b52fc5e6d6b9219477d69870fa99c6af65ed94dee?s=96&d=monsterid&r=g\",\"caption\":\"marciaaaaal\"},\"sameAs\":[\"http:\\\/\\\/www.todoheavymetal.com\\\/\"],\"url\":\"https:\\\/\\\/www.todoheavymetal.com\\\/index.php\\\/author\\\/marciaaaaal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA - HEAVY METAL - NOTICIAS HEAVY METAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida","og_locale":"es_ES","og_type":"article","og_title":"ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA - HEAVY METAL - NOTICIAS HEAVY METAL","og_description":"todoheavymetal se puso en contacto con la emergente banda murciana de power metal mel\u00f3dico, SIR\u00c1CIDA, para que nos contaran de primera mano c\u00f3mo est\u00e1 siendo la aceptaci\u00f3n de su primer trabajo Del Coraz\u00f3n al Alma y nos contaran las \u00faltimas noticias referentes a la banda. A continuaci\u00f3n os ponemos la interesante entrevista mantenida con Juanjo [&hellip;]","og_url":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida","og_site_name":"HEAVY METAL - NOTICIAS HEAVY METAL","article_publisher":"https:\/\/www.facebook.com\/todoheavymetal\/","article_published_time":"2012-07-10T16:00:50+00:00","article_modified_time":"2012-07-10T21:13:00+00:00","og_image":[{"url":"http:\/\/4.bp.blogspot.com\/_RpfwmfKwJwg\/TQXq77MVRBI\/AAAAAAAAAGY\/zusAphveUWU\/s1600\/disco.jpg","type":"","width":"","height":""}],"author":"marciaaaaal","twitter_card":"summary_large_image","twitter_creator":"@todoheavymetal","twitter_site":"@todoheavymetal","twitter_misc":{"Escrito por":"marciaaaaal","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida#article","isPartOf":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida"},"author":{"name":"marciaaaaal","@id":"https:\/\/www.todoheavymetal.com\/#\/schema\/person\/e3170256584bfef679ff987358c5cabc"},"headline":"ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA","datePublished":"2012-07-10T16:00:50+00:00","dateModified":"2012-07-10T21:13:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida"},"wordCount":3005,"commentCount":0,"image":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida#primaryimage"},"thumbnailUrl":"http:\/\/4.bp.blogspot.com\/_RpfwmfKwJwg\/TQXq77MVRBI\/AAAAAAAAAGY\/zusAphveUWU\/s1600\/disco.jpg","keywords":["ENTREVISTA A JUANJO RUIZ BATER\u00cdA DE SIR\u00c1CIDA todoheavymetal.com","ENTREVISTA A SIR\u00c1CIDA todoheavymetal.com","sir\u00e1cida todoheavymetal.com"],"articleSection":["ENTREVISTAS","Noticias del mes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida","url":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida","name":"ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA - HEAVY METAL - NOTICIAS HEAVY METAL","isPartOf":{"@id":"https:\/\/www.todoheavymetal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida#primaryimage"},"image":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida#primaryimage"},"thumbnailUrl":"http:\/\/4.bp.blogspot.com\/_RpfwmfKwJwg\/TQXq77MVRBI\/AAAAAAAAAGY\/zusAphveUWU\/s1600\/disco.jpg","datePublished":"2012-07-10T16:00:50+00:00","dateModified":"2012-07-10T21:13:00+00:00","author":{"@id":"https:\/\/www.todoheavymetal.com\/#\/schema\/person\/e3170256584bfef679ff987358c5cabc"},"breadcrumb":{"@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida#primaryimage","url":"http:\/\/4.bp.blogspot.com\/_RpfwmfKwJwg\/TQXq77MVRBI\/AAAAAAAAAGY\/zusAphveUWU\/s1600\/disco.jpg","contentUrl":"http:\/\/4.bp.blogspot.com\/_RpfwmfKwJwg\/TQXq77MVRBI\/AAAAAAAAAGY\/zusAphveUWU\/s1600\/disco.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.todoheavymetal.com\/index.php\/noticias-del-mes\/entrevista-a-juanjo-ruiz-bateria-de-siracida#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.todoheavymetal.com\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA A JUANJO RUIZ, BATER\u00cdA DE SIR\u00c1CIDA"}]},{"@type":"WebSite","@id":"https:\/\/www.todoheavymetal.com\/#website","url":"https:\/\/www.todoheavymetal.com\/","name":"todoheavymetal.com","description":"heavy metal - noticias heavy metal - todoheavymetal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todoheavymetal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.todoheavymetal.com\/#\/schema\/person\/e3170256584bfef679ff987358c5cabc","name":"marciaaaaal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/57d360e5d1ff29399da35b7b52fc5e6d6b9219477d69870fa99c6af65ed94dee?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57d360e5d1ff29399da35b7b52fc5e6d6b9219477d69870fa99c6af65ed94dee?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57d360e5d1ff29399da35b7b52fc5e6d6b9219477d69870fa99c6af65ed94dee?s=96&d=monsterid&r=g","caption":"marciaaaaal"},"sameAs":["http:\/\/www.todoheavymetal.com\/"],"url":"https:\/\/www.todoheavymetal.com\/index.php\/author\/marciaaaaal"}]}},"_links":{"self":[{"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/posts\/13341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/comments?post=13341"}],"version-history":[{"count":3,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/posts\/13341\/revisions"}],"predecessor-version":[{"id":13343,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/posts\/13341\/revisions\/13343"}],"wp:attachment":[{"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/media?parent=13341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/categories?post=13341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoheavymetal.com\/index.php\/wp-json\/wp\/v2\/tags?post=13341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}